{"id":6867,"date":"2026-08-21T14:17:08","date_gmt":"2026-08-21T17:17:08","guid":{"rendered":"https:\/\/vohnabrindes.com.br\/?post_type=product&#038;p=6867"},"modified":"2026-08-21T14:17:28","modified_gmt":"2026-08-21T17:17:28","slug":"kit-executivo-4-pecas-personalizado","status":"publish","type":"product","link":"https:\/\/vohnabrindes.com.br\/index.php\/product\/kit-executivo-4-pecas-personalizado\/","title":{"rendered":"Kit Executivo 4 Pe\u00e7as Personalizado."},"content":{"rendered":"<pre id=\"item_referencia\">19220<\/pre>\n<p class=\"produto-nome\">Kit Executivo 4 Pe\u00e7as Personalizado.<\/p>\n<div class=\"caracs\">\n<div class=\"desc\">\n<p class=\"desc-tit\">Descri\u00e7\u00e3o:\u00a0<span class=\"desc-sub my-desc-sub\">Kit composto por quatro itens: caderneta, caneta, porta-cart\u00e3o e chaveiro. A caderneta possui capa em poliuretano (PU), marca-p\u00e1ginas em fita de cetim e aproximadamente 76 folhas marfim pautadas. A caneta met\u00e1lica conta com tampa e carga esferogr\u00e1fica preta de 0,7mm. O porta-cart\u00f5es apresenta estrutura em inox com revestimento externo em PU e interior aveludado, al\u00e9m de plaquinha frontal personaliz\u00e1vel. O chaveiro \u00e9 constru\u00eddo em PU texturizado com argola e chapa em liga de zinco. Acompanha caixa em papel\u00e3o com ber\u00e7o remov\u00edvel em pl\u00e1stico de acabamento aveludado para acomoda\u00e7\u00e3o dos itens do conjunto.<\/span><\/p>\n<\/div>\n<div class=\"desc\">\n<p class=\"desc-tit\">Altura<span class=\"desc-sub\"> :\u00a0 16,7 cm x <\/span>Largura<span class=\"desc-sub\"> :\u00a0 25,8 cm x <\/span>Profundidade<span class=\"desc-sub\">\u00a0:\u00a0 2,2 cm<\/span><\/p>\n<\/div>\n<div class=\"desc\">\n<p class=\"desc-tit\">peso aproximado<span class=\"desc-sub\">\u00a0(g):\u00a0 341<\/span><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>19220 Kit Executivo 4 Pe\u00e7as Personalizado. Descri\u00e7\u00e3o:\u00a0Kit composto por quatro itens: caderneta, caneta, porta-cart\u00e3o e chaveiro. A caderneta possui capa em poliuretano (PU), marca-p\u00e1ginas em fita<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"featured_media":6879,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[165],"product_tag":[697,2594,1079],"class_list":["post-6867","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-escritorio-e-conjuntos-executivos","product_tag-kit-escritorio-personalizado","product_tag-kit-executivo-4-pecas-personalizado","product_tag-kit-executivo-personalizado"],"_links":{"self":[{"href":"https:\/\/vohnabrindes.com.br\/index.php\/wp-json\/wp\/v2\/product\/6867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vohnabrindes.com.br\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/vohnabrindes.com.br\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/vohnabrindes.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6867"}],"version-history":[{"count":1,"href":"https:\/\/vohnabrindes.com.br\/index.php\/wp-json\/wp\/v2\/product\/6867\/revisions"}],"predecessor-version":[{"id":6880,"href":"https:\/\/vohnabrindes.com.br\/index.php\/wp-json\/wp\/v2\/product\/6867\/revisions\/6880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vohnabrindes.com.br\/index.php\/wp-json\/wp\/v2\/media\/6879"}],"wp:attachment":[{"href":"https:\/\/vohnabrindes.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6867"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/vohnabrindes.com.br\/index.php\/wp-json\/wp\/v2\/product_cat?post=6867"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/vohnabrindes.com.br\/index.php\/wp-json\/wp\/v2\/product_tag?post=6867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}